{"id":1789,"date":"2024-02-21T11:29:21","date_gmt":"2024-02-21T10:29:21","guid":{"rendered":"https:\/\/wiwi-foerderverein.aau.at\/?p=1789"},"modified":"2024-03-07T14:45:49","modified_gmt":"2024-03-07T13:45:49","slug":"ausschreibung-wr-awards-2024","status":"publish","type":"post","link":"https:\/\/wiwi-foerderverein.aau.at\/index.php\/2024\/02\/21\/ausschreibung-wr-awards-2024\/","title":{"rendered":"Ausschreibung W&#038;R-Awards 2024"},"content":{"rendered":"<p>Die W&amp;R-Fakult\u00e4t schreibt auch im aktuellen Studienjahr drei Awards und zwar in den Kategorien Best Paper, Lehre und Students aus. Die Awards werden vom Verein zur F\u00f6rderung der W&amp;R gesponsert. Die Verleihung findet am 19. November 2024 um 18 Uhr an der AAU statt.<\/p>\n\n\n<!--more -->\n\n\n<p>Jeder der drei Awards ist mit 2.000 Euro dotiert.<\/p>\n<p><a href=\"https:\/\/wiwi-foerderverein.aau.at\/wp-content\/uploads\/2024\/02\/WR_BestPaperAward2024.pdf\" target=\"_blank\" rel=\"noopener\">Ausschreibung W&amp;R Best Paper Award 2024<\/a><\/p>\n<p><a href=\"https:\/\/wiwi-foerderverein.aau.at\/wp-content\/uploads\/2024\/02\/WR_Lehrpreis-2023-24.pdf\" target=\"_blank\" rel=\"noopener\">Ausschreibung W&amp;R Lehrpreis 2024<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Die W&amp;R-Fakult\u00e4t schreibt auch im aktuellen Studienjahr drei Awards und zwar in den Kategorien Best Paper, Lehre und Students aus. Die Awards [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1789","post","type-post","status-publish","format-standard","hentry","category-aktuelles"],"_links":{"self":[{"href":"https:\/\/wiwi-foerderverein.aau.at\/index.php\/wp-json\/wp\/v2\/posts\/1789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wiwi-foerderverein.aau.at\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wiwi-foerderverein.aau.at\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wiwi-foerderverein.aau.at\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wiwi-foerderverein.aau.at\/index.php\/wp-json\/wp\/v2\/comments?post=1789"}],"version-history":[{"count":11,"href":"https:\/\/wiwi-foerderverein.aau.at\/index.php\/wp-json\/wp\/v2\/posts\/1789\/revisions"}],"predecessor-version":[{"id":2050,"href":"https:\/\/wiwi-foerderverein.aau.at\/index.php\/wp-json\/wp\/v2\/posts\/1789\/revisions\/2050"}],"wp:attachment":[{"href":"https:\/\/wiwi-foerderverein.aau.at\/index.php\/wp-json\/wp\/v2\/media?parent=1789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wiwi-foerderverein.aau.at\/index.php\/wp-json\/wp\/v2\/categories?post=1789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wiwi-foerderverein.aau.at\/index.php\/wp-json\/wp\/v2\/tags?post=1789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}